{"id":2684,"date":"2021-02-15T22:32:57","date_gmt":"2021-02-15T22:32:57","guid":{"rendered":"https:\/\/trytogiveback.org\/?page_id=2684"},"modified":"2021-04-08T16:34:55","modified_gmt":"2021-04-08T16:34:55","slug":"climate_change_global_warming","status":"publish","type":"page","link":"https:\/\/trytogiveback.org\/it\/climate_change_global_warming\/","title":{"rendered":"Cambiamento Climatico"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2684\" class=\"elementor elementor-2684\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7bce23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7bce23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c59908a\" data-id=\"c59908a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4488189 elementor-widget elementor-widget-heading\" data-id=\"4488189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAMBIAMENTO CLIMATICO E RISCALDAMENTO GLOBALE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0eeed36 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0eeed36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb59c1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb59c1c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0eec1c9\" data-id=\"0eec1c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d59e529 elementor-widget elementor-widget-image\" data-id=\"d59e529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"525\" src=\"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg\" class=\"attachment-large size-large wp-image-2686\" alt=\"\" srcset=\"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg 1024w, https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-300x154.jpg 300w, https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-768x394.jpg 768w, https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-16x8.jpg 16w, https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-916c7ee\" data-id=\"916c7ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc4c510 elementor-widget elementor-widget-heading\" data-id=\"bc4c510\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\" SE SIAMO DIVENTATI ABBASTANZA POTENTI DA CAMBIARE L'INTERO PIANETA, ALLORA SIAMO ABBASTANZA POTENTI PER LAVORARE CON LA NATURA PIUTTOSTO CHE CONTRO DI ESSA\". <br>\n- David Attenborough-\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-076f518 elementor-widget elementor-widget-text-editor\" data-id=\"076f518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il clima della Terra \u00e8 cambiato nel corso della storia. Solo negli ultimi 650.000 anni ci sono stati sette cicli di avanzamento e ritiro dei ghiacciai, con la fine improvvisa dell'ultima era glaciale circa 11.700 anni fa che ha segnato l'inizio dell'era climatica moderna - e della civilt\u00e0 umana. La maggior parte di questi cambiamenti climatici e attribuita a piccolissime variazioni dell'orbita terrestre che cambiano la quantit\u00e0 di energia solare che il nostro pianeta riceve.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f9ea0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f9ea0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2bee74\" data-id=\"f2bee74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a6b29a elementor-widget elementor-widget-text-editor\" data-id=\"2a6b29a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>L'evidenza scientifica del riscaldamento del sistema climatico \u00e8 inequivocabile.<\/strong><\/p><p>L'attuale tendenza al riscaldamento \u00e8 particolarmente significativa perch\u00e9 la maggior parte di essa \u00e8 estremamente probabile (pi\u00f9 del 95% di probabilit\u00e0) che sia il risultato dell'attivit\u00e0 umana dalla met\u00e0 del 20\u00b0 secolo e che proceda a un ritmo che non ha precedenti da decenni a millenni.<\/p><p>I satelliti in orbita intorno alla Terra e altri progressi tecnologici hanno permesso agli scienziati di vedere il quadro generale, raccogliendo diverse informazioni sul nostro pianeta e il suo clima su scala globale. Questo insieme di dati, raccolti nel corso di molti anni, rivela i segnali di un clima che cambia.<\/p><p>La natura di intrappolamento del calore dell'anidride carbonica e di altri gas \u00e8 stata dimostrata a met\u00e0 del 19\u00b0 secolo. La loro capacit\u00e0 di influenzare il trasferimento di energia infrarossa attraverso l'atmosfera \u00e8 la base scientifica di molti strumenti inviati dalla NASA. Non c'\u00e8 dubbio che l'aumento dei livelli di gas a effetto serra causi il riscaldamento della Terra.<\/p><p>Le carote di ghiaccio prelevate dalla Groenlandia, dall'Antartide e dai ghiacciai delle montagne tropicali mostrano che il clima della Terra risponde ai cambiamenti dei livelli di gas serra. Prove antiche possono anche essere trovate negli anelli degli alberi, nei sedimenti oceanici, nelle barriere coralline e negli strati di rocce sedimentarie. Queste prove antiche, o paleoclimatiche, rivelano che il riscaldamento attuale sta avvenendo circa dieci volte pi\u00f9 velocemente del tasso medio di riscaldamento dell'era glaciale. L'anidride carbonica proveniente dall'attivit\u00e0 umana sta aumentando pi\u00f9 di 250 volte pi\u00f9 velocemente di quella proveniente da fonti naturali dopo l'ultima era glaciale.<\/p><p><strong>Le prove di un rapido cambiamento climatico sono convincenti:<\/strong><\/p><p><strong>Aumento globale della temperatura<\/strong><\/p><p>La temperatura media della superficie del pianeta \u00e8 aumentata di circa 2,12 gradi Fahrenheit (1,18 gradi Celsius) dalla fine del XIX secolo, un cambiamento guidato in gran parte dall'aumento delle emissioni di anidride carbonica nell'atmosfera e da altre attivit\u00e0 umane. La maggior parte del riscaldamento \u00e8 avvenuta negli ultimi 40 anni, e i sette anni pi\u00f9 recenti sono stati i pi\u00f9 caldi. Il 2016 e il 2020 sono a pari merito i anni pi\u00f9 caldi mai registrati.<\/p><p><strong>Riscaldamento dell'oceano<\/strong><\/p><p>L'oceano ha assorbito gran parte di questo aumento di calore, con i primi 100 metri di oceano che mostrano un riscaldamento di pi\u00f9 di 0,6 gradi Fahrenheit (0,33 gradi Celsius) dal 1969. La Terra immagazzina il 90% dell'energia extra nell'oceano.<\/p><p><strong>Ghiacciai che si restringono<\/strong><\/p><p>Le lastre di ghiaccio della Groenlandia e dell'Antartide sono diminuite di massa. I dati del Gravity Recovery and Climate Experiment della NASA mostrano che la Groenlandia ha perso una media di 279 miliardi di tonnellate di ghiaccio all'anno tra il 1993 e il 2019, mentre l'Antartide ha perso circa 148 miliardi di tonnellate di ghiaccio all'anno.<\/p><p><strong>Ritiro glaciale<\/strong><\/p><p>I ghiacciai si stanno ritirando quasi ovunque nel mondo - anche nelle Alpi, Himalaya, Ande, Montagne Rocciose, Alaska e Africa.<\/p><p><strong>Diminuzione della copertura nevosa<\/strong><\/p><p>Le osservazioni satellitari rivelano che la quantit\u00e0 di copertura nevosa primaverile nell'emisfero settentrionale \u00e8 diminuita negli ultimi cinque decenni e la neve si sta sciogliendo prima.<\/p><p><strong>Aumento del livello del mare<\/strong><\/p><p>Il livello globale del mare \u00e8 aumentato di circa 20 cm nell'ultimo secolo. Il tasso negli ultimi due decenni, tuttavia, \u00e8 quasi il doppio di quello del secolo scorso e sta accelerando leggermente ogni anno.<\/p><p><strong>Declino del ghiaccio marino artico<\/strong><\/p><p>Sia l'estensione che lo spessore del ghiaccio marino Artico sono diminuiti rapidamente negli ultimi decenni.<\/p><p><strong>Eventi estremi<\/strong><\/p><p>Il numero di eventi di alta temperatura record negli Stati Uniti \u00e8 aumentato, mentre il numero di eventi di bassa temperatura record \u00e8 diminuito, dal 1950. Gli Stati Uniti hanno anche assistito a un numero crescente di eventi di precipitazioni intense.<\/p><p><strong>Acidificazione dell'oceano<\/strong><\/p><p>Dall'inizio della rivoluzione industriale, l'acidit\u00e0 delle acque oceaniche superficiali \u00e8 aumentata di circa il 30%. Questo aumento \u00e8 il risultato dell'uomo che emette pi\u00f9 anidride carbonica nell'atmosfera e quindi viene assorbita dall'oceano. L'oceano ha assorbito tra il 20% e il 30% delle emissioni totali di anidride carbonica antropogenica negli ultimi decenni (da 7,2 a 10,8 miliardi di tonnellate metriche all'anno).<\/p><p><strong>Le cause del cambiamento climatico<\/strong><\/p><p>Gli scienziati attribuiscono la tendenza al riscaldamento globale osservata dalla met\u00e0 del 20\u00b0 secolo all'espansione umana dell'\"effetto serra\" - il riscaldamento che risulta quando l'atmosfera intrappola il calore che si irradia dalla Terra verso lo spazio.<\/p><p>Alcuni gas nell'atmosfera bloccano la fuoriuscita di calore. I gas a lunga vita che rimangono semipermanentemente nell'atmosfera e non rispondono fisicamente o chimicamente ai cambiamenti di temperatura sono descritti come \"forzanti\" del cambiamento climatico. I gas, come il vapore acqueo, che rispondono fisicamente o chimicamente ai cambiamenti di temperatura sono visti come \"feedback\".<\/p><p>I gas che contribuiscono all'effetto serra includono:<\/p><ul><li><u>Vapore acqueo.<\/u>Il gas serra pi\u00f9 abbondante, ma soprattutto, agisce come feedback al clima. Il vapore acqueo aumenta con il riscaldamento dell'atmosfera terrestre, ma anche la possibilit\u00e0 di nuvole e precipitazioni, costituiscono alcuni dei pi\u00f9 importanti meccanismi di feedback all'effetto serra.<\/li><\/ul><ul><li><u>Anidride carbonica (CO2).<\/u>Componente minore ma molto importante dell'atmosfera, l'anidride carbonica viene rilasciata attraverso processi naturali come la respirazione e le eruzioni vulcaniche e attraverso attivit\u00e0 umane come la deforestazione, i cambiamenti di uso del suolo e la combustione di combustibili fossili. Gli esseri umani hanno aumentato la concentrazione di CO2 nell'atmosfera del 47% dall'inizio della rivoluzione industriale. Questa \u00e8 la pi\u00f9 importante \"forzatura\" a lungo termine del cambiamento climatico.<\/li><\/ul><ul><li><u>Metano.<\/u>Un gas idrocarburo prodotto sia da fonti naturali che da attivit\u00e0 umane, compresa la decomposizione dei rifiuti nelle discariche, l'agricoltura e soprattutto la coltivazione del riso, cos\u00ec come la digestione dei ruminanti e la gestione del letame associato al bestiame domestico. Su una base molecola per molecola, il metano \u00e8 un gas serra molto pi\u00f9 attivo dell'anidride carbonica, ma anche molto meno abbondante nell'atmosfera.<\/li><\/ul><ul><li><u>Protossido di azoto.<\/u>Un potente gas a effetto serra prodotto dalle pratiche di coltivazione del suolo, specialmente l'uso di fertilizzanti commerciali e organici, la combustione di combustibili fossili, la produzione di acido nitrico e la combustione di biomassa.<\/li><\/ul><ul><li><u>Clorofluorocarburi (CFC).<\/u>Composti sintetici interamente di origine industriale utilizzati in una serie di applicazioni, ma ora ampiamente regolati nella produzione e nel rilascio nell'atmosfera da accordi internazionali per la loro capacit\u00e0 di contribuire alla distruzione dello strato di ozono. Sono anche gas a effetto serra.<\/li><\/ul><p>Sulla Terra, le attivit\u00e0 umane stanno cambiando l'effetto serra naturale. Nell'ultimo secolo la combustione di combustibili fossili come il carbone e il petrolio ha aumentato la concentrazione di anidride carbonica atmosferica (CO2). Questo accade perch\u00e9 il processo di combustione del carbone o del petrolio combina il carbonio con l'ossigeno nell'aria per produrre CO2. In misura minore, il disboscamento della terra per l'agricoltura, l'industria e altre attivit\u00e0 umane ha aumentato le concentrazioni di gas serra.<\/p><p><strong>Le conseguenze del cambiamento della serra atmosferica naturale sono:<\/strong><\/p><p>In media, la Terra diventer\u00e0 pi\u00f9 calda. Alcune regioni potrebbero accogliere temperature pi\u00f9 calde, ma altre no.<\/p><p>Le condizioni pi\u00f9 calde porteranno probabilmente a una maggiore evaporazione e precipitazioni in generale, ma le singole regioni varieranno, alcune diventeranno pi\u00f9 umide e altre pi\u00f9 secche.<\/p><p>Un effetto serra pi\u00f9 forte riscalder\u00e0 l'oceano e scioglier\u00e0 parzialmente i ghiacciai e le lastre di ghiaccio, aumentando il livello del mare. Anche l'acqua dell'oceano si espander\u00e0 se si riscalda, contribuendo ulteriormente all'aumento del livello del mare.<\/p><p>Al di fuori di una serra, livelli pi\u00f9 alti di anidride carbonica atmosferica (CO2) possono avere effetti sia positivi che negativi sui raccolti. Alcuni esperimenti di laboratorio suggeriscono che livelli elevati di CO2 possono aumentare la crescita delle piante. Tuttavia, altri fattori, come il cambiamento delle temperature, l'ozono, l'acqua e i vincoli nutrizionali, possono pi\u00f9 che contrastare qualsiasi potenziale aumento della resa. Se le gamme di temperatura ottimali per alcune colture vengono superate, i possibili guadagni precedenti nella resa possono essere ridotti o invertiti del tutto.<\/p><p>Gli estremi climatici, come siccit\u00e0, inondazioni e temperature estreme, possono portare a perdite di raccolto e minacciare il sostentamento dei produttori agricoli e la sicurezza alimentare delle comunit\u00e0 di tutto il mondo. A seconda della coltura e dell'ecosistema, le erbacce, i parassiti e i funghi possono anche prosperare con temperature pi\u00f9 calde, climi pi\u00f9 umidi e un aumento dei livelli di CO2, e il cambiamento climatico probabilmente aumenter\u00e0 le erbacce e i parassiti.<\/p><p>Infine, anche se l'aumento di CO2 pu\u00f2 stimolare la crescita delle piante, la ricerca ha dimostrato che pu\u00f2 anche ridurre il valore nutrizionale della maggior parte delle colture alimentari, riducendo le concentrazioni di proteine e minerali essenziali nella maggior parte delle specie vegetali. Il cambiamento climatico pu\u00f2 far emergere nuovi modelli di parassiti e malattie che colpiscono piante, animali ed esseri umani e che pongono nuovi rischi per la sicurezza alimentare e la salute umana.<\/p><p><strong>Il ruolo dell'attivit\u00e0 umana<\/strong><\/p><p>Nel suo quinto rapporto di valutazione, l'Intergovernmental Panel on Climate Change, un gruppo di 1.300 esperti scientifici indipendenti provenienti da paesi di tutto il mondo sotto l'egida delle Nazioni Unite, ha concluso che c'\u00e8 una probabilit\u00e0 superiore al 95% che le attivit\u00e0 umane negli ultimi 50 anni abbiano riscaldato il nostro pianeta.<\/p><p>Le attivit\u00e0 industriali da cui dipende la nostra civilt\u00e0 moderna hanno aumentato i livelli di anidride carbonica atmosferica da 280 parti per milione a 414 parti per milione negli ultimi 150 anni. La commissione ha anche concluso che c'\u00e8 una probabilit\u00e0 superiore al 95% che i gas serra prodotti dall'uomo come l'anidride carbonica, il metano e il protossido d'azoto abbiano causato gran parte dell'aumento osservato nelle temperature della Terra negli ultimi 50 anni.<\/p><p>\u00c8 ragionevole supporre che i cambiamenti nella produzione di energia del Sole causino un cambiamento del clima, poich\u00e9 il Sole \u00e8 la fonte fondamentale di energia che guida il nostro sistema climatico.<\/p><p>Infatti, gli studi dimostrano che la variabilit\u00e0 solare ha giocato un ruolo nei cambiamenti climatici del passato. Per esempio, si pensa che una diminuzione dell'attivit\u00e0 solare unita a un aumento dell'attivit\u00e0 vulcanica abbia contribuito a innescare la Piccola Era Glaciale tra il 1650 e il 1850 circa, quando la Groenlandia si raffredd\u00f2 dal 1410 al 1720 e i ghiacciai avanzarono nelle Alpi.<\/p><p>Ma diverse linee di prova dimostrano che l'attuale riscaldamento globale non pu\u00f2 essere spiegato da cambiamenti nell'energia del Sole:<\/p><p>Dal 1750, la quantit\u00e0 media di energia proveniente dal Sole \u00e8 rimasta costante o \u00e8 leggermente aumentata. Se il riscaldamento fosse causato da un Sole pi\u00f9 attivo, allora gli scienziati si aspetterebbero di vedere temperature pi\u00f9 calde in tutti gli strati dell'atmosfera. Invece, hanno osservato un raffreddamento nell'atmosfera superiore, e un riscaldamento in superficie e nelle parti pi\u00f9 basse dell'atmosfera. Questo perch\u00e9 i gas a effetto serra intrappolano il calore nell'atmosfera inferiore.<\/p><p>I modelli climatici che includono i cambiamenti dell'irraggiamento solare non possono riprodurre la tendenza della temperatura osservata nell'ultimo secolo o pi\u00f9 senza includere un aumento dei gas a effetto serra.<\/p><p><strong>Gli effetti del cambiamento climatico<\/strong><\/p><p>Il cambiamento climatico globale ha gi\u00e0 avuto effetti osservabili sull'ambiente. I ghiacciai si sono ridotti, il ghiaccio su fiumi e laghi si sta rompendo prima, le gamme di piante e animali si sono spostate e gli alberi fioriscono prima.<\/p><p>Gli effetti che gli scienziati avevano previsto in passato sarebbero stati causati dal cambiamento climatico globale si stanno ora verificando: perdita di ghiaccio marino, aumento accelerato del livello del mare e onde di calore pi\u00f9 lunghe e intense.<\/p><p>Gli scienziati sono sicuri che le temperature globali continueranno ad aumentare per i decenni a venire, in gran parte a causa dei gas serra prodotti dalle attivit\u00e0 umane. Il Gruppo intergovernativo sui cambiamenti climatici (IPCC), che comprende pi\u00f9 di 1.300 scienziati degli Stati Uniti e di altri paesi, prevede un aumento della temperatura da 2,5 a 10 gradi Fahrenheit nel prossimo secolo.<\/p><p>According to the IPCC, the extent of climate change effects on individual regions will vary over time and with the ability of different societal and environmental systems to mitigate or adapt to change.<\/p><p>The IPCC predicts that increases in global mean temperature of less than 1.8 to 5.4 degrees Fahrenheit (1 to 3 degrees Celsius) above 1990 levels will produce beneficial impacts in some regions and harmful ones in others. Net annual costs will increase over time as global temperatures increase.<\/p><p><strong>Effetti futuri<\/strong><\/p><p>Alcuni degli effetti a lungo termine del cambiamento climatico globale negli Stati Uniti sono i seguenti, secondo il terzo e quarto rapporto nazionale di valutazione del clima:<\/p><p><strong>Il Cambiamento Continuer\u00e0 per Tutto il Secolo e Oltre<\/strong><\/p><p>Si prevede che il clima globale continuer\u00e0 a cambiare nel corso di questo secolo e oltre. L'ampiezza del cambiamento climatico oltre i prossimi decenni dipende principalmente dalla quantit\u00e0 di gas che intrappolano il calore emessi a livello globale, e da quanto il clima della Terra \u00e8 sensibile a queste emissioni.<\/p><p><strong>Le Temperature Continueranno a Salire<\/strong><\/p><p>Poich\u00e9 il riscaldamento indotto dall'uomo si sovrappone a un clima che varia naturalmente, l'aumento della temperatura non \u00e8 stato, e non sar\u00e0, uniforme o regolare in tutto il paese o nel tempo.<\/p><p><strong>La Stagione Senza Gelo (e la stagione di crescita) si Allunga<\/strong><\/p><p>L\u2019aumento della durata di una stagione di crescita (in qualsivoglia regione) si riferisce al numero di giorni in cui avviene la crescita delle piante. La stagione di crescita spesso determina quali colture possono essere coltivate in una zona, poich\u00e9 alcune colture richiedono lunghe stagioni di crescita, mentre altre maturano rapidamente. La lunghezza della stagione di crescita \u00e8 limitata da molti fattori diversi. A seconda della regione e del clima, la stagione di crescita \u00e8 influenzata dalle temperature dell'aria, dai giorni di gelo, dalle piogge o dalle ore di luce del giorno.<\/p><p><br \/>I cambiamenti nella lunghezza della stagione di crescita possono avere effetti sia positivi che negativi sulla resa e sui prezzi di particolari colture. In generale, ci si aspetta che il riscaldamento abbia effetti negativi sulla resa delle principali colture, ma le colture in alcune singole localit\u00e0 potrebbero trarne beneficio.1 Una stagione di crescita pi\u00f9 lunga potrebbe permettere agli agricoltori di diversificare le colture o avere pi\u00f9 raccolti dallo stesso appezzamento. Tuttavia, potrebbe anche limitare i tipi di coltivazioni, incoraggiare la crescita di specie invasive o di erbacce, o aumentare la domanda di irrigazione. Una stagione di crescita pi\u00f9 lunga potrebbe anche sconvolgere la funzione e la struttura degli ecosistemi di una regione e potrebbe, per esempio, alterare la gamma e i tipi di specie animali nella zona.<\/p><p><strong>Cambiamenti nei Modelli di Precipitazione<\/strong><\/p><p>Gli attuali modelli climatici indicano che l'aumento delle temperature intensificher\u00e0 il ciclo dell'acqua della Terra, aumentando l'evaporazione. L'aumento dell'evaporazione porter\u00e0 a tempeste pi\u00f9 frequenti e intense, ma contribuir\u00e0 anche all'inaridimento di alcune aree terrestri. Di conseguenza, le aree colpite dalle tempeste probabilmente sperimenteranno un aumento delle precipitazioni e un maggior rischio di inondazioni, mentre le aree situate lontano dai percorsi delle tempeste probabilmente sperimenteranno meno precipitazioni e un maggior rischio di siccit\u00e0.<\/p><p><strong>Pi\u00f9 Siccit\u00e0 e Ondate di Calore<\/strong><\/p><p>Un'ondata di calore \u00e8 generalmente definita come un periodo di diversi giorni o settimane di tempo anormalmente caldo.<\/p><p>Negli ultimi 3-4 decenni, c'\u00e8 stata una tendenza crescente nelle ondate di calore ad alta umidit\u00e0, che sono caratterizzate dalla persistenza di temperature notturne estremamente elevate. La combinazione di alta umidit\u00e0 e alta temperatura notturna pu\u00f2 costituire un'accoppiata mortale, che non offre sollievo e costituisce una minaccia particolare per gli anziani. Gli eventi di calore estremo sono responsabili ogni anno di pi\u00f9 morti di uragani, fulmini, tornado, inondazioni e terremoti messi insieme.<\/p><p>Allo stesso tempo, le ondate di calore a bassa umidit\u00e0 associate alla siccit\u00e0 e alimentate in parte dal cambiamento climatico contribuiscono alle condizioni di siccit\u00e0 che spingono gli incendi selvaggi.<\/p><p>Numerosi studi hanno documentato che il cambiamento climatico indotto dall'uomo ha aumentato la frequenza e la gravit\u00e0 delle ondate di calore in tutto il mondo.<\/p><p><strong>Gli uragani diventeranno pi\u00f9 forti e pi\u00f9 intensi<\/strong><\/p><p>L'intensit\u00e0, la frequenza e la durata degli uragani del Nord Atlantico, cos\u00ec come la frequenza degli uragani pi\u00f9 forti (categoria 4 e 5), sono tutti aumentati dai primi anni '80<\/p><p>I contributi relativi delle cause umane e naturali a questi aumenti sono ancora incerti. Si prevede che l'intensit\u00e0 delle tempeste associate agli uragani e i tassi di precipitazione aumenteranno con il continuo riscaldamento del clima.<\/p><p><strong>Il Livello del Mare si Alzer\u00e0<\/strong><\/p><p>Il livello globale del mare \u00e8 aumentato di circa 8 pollici da quando sono iniziate le registrazioni affidabili nel 1880. Si prevede che aumenter\u00e0 di altri 1 o 4 piedi entro il 2100. Questo \u00e8 il risultato dell'acqua aggiunta dallo scioglimento dei ghiacci terrestri e dall'espansione dell'acqua del mare quando si riscalda.<\/p><p>Nei prossimi decenni, le tempeste e le alte maree potrebbero combinarsi con l'aumento del livello del mare e la subsidenza del terreno per aumentare ulteriormente le inondazioni in molte regioni. L'aumento del livello del mare continuer\u00e0 oltre il 2100 perch\u00e9 gli oceani impiegano un tempo molto lungo per rispondere a condizioni pi\u00f9 calde sulla superficie terrestre. Le acque degli oceani continueranno quindi a riscaldarsi e il livello del mare continuer\u00e0 a salire per molti secoli a tassi uguali o superiori a quelli del secolo corrente.<\/p><p><strong>L'Artico Rischia di Diventare Privo di Ghiaccio<\/strong><\/p><p>Ci si aspetta che l'Oceano Artico diventi essenzialmente privo di ghiaccio in estate prima della met\u00e0 del secolo.<\/p><p><strong>Soluzioni per aiutare a risolvere il cambiamento climatico:<\/strong><\/p><p><a href=\"https:\/\/trytogiveback.org\/it\/deforestation\/\">Piantare regolarmente alberi <\/a><\/p><p><a href=\"https:\/\/trytogiveback.org\/it\/healthy-eating-habits\/\">Abitudini alimentari sane<\/a><\/p><p><a href=\"https:\/\/trytogiveback.org\/it\/sustainable_living\/\">Vita sostenibile<\/a><\/p><p><a href=\"https:\/\/trytogiveback.org\/it\/plastic_pollution\/\">Dire no alla plastica<\/a><\/p><p><a href=\"https:\/\/trytogiveback.org\/it\/population\/\">Popolazione<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab6486 elementor-widget elementor-widget-text-editor\" data-id=\"6ab6486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>fonti:<\/strong><\/p><p><a href=\"https:\/\/climate.nasa.gov\/\" target=\"_blank\" rel=\"noopener\">www.climate.nasa.gov\/<\/a><\/p><p><a href=\"https:\/\/www.epa.gov\/climate-indicators\/climate-change-indicators-length-growing-season\" target=\"_blank\" rel=\"noopener\">https:\/\/www.epa.gov\/<\/a><\/p><p><a href=\"https:\/\/www.climatecommunication.org\/new\/features\/heat-waves-and-climate-change\/heat-waves-the-details\/\" target=\"_blank\" rel=\"noopener\">www.climatecommunication.org<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CLIMATE CHANGE AND GLOBAL WARMING &#8221; IF WE HAVE BECOME POWERFUL ENOUGH TO CHANGE THE ENTIRE PLANET, THEN WE ARE POWERFUL ENOUGH TO WORK WITH NATURE RATHER THAN AGAINST IT &#8221; &#8211; David Attenborough- Earth&#8217;s climate has changed throughout history. Just in the last 650,000 years there have been seven cycles of glacial advance and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2684","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Climate Change - Alveto Expedition<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trytogiveback.org\/it\/climate_change_global_warming\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Climate Change - Alveto Expedition\" \/>\n<meta property=\"og:description\" content=\"CLIMATE CHANGE AND GLOBAL WARMING &#8221; IF WE HAVE BECOME POWERFUL ENOUGH TO CHANGE THE ENTIRE PLANET, THEN WE ARE POWERFUL ENOUGH TO WORK WITH NATURE RATHER THAN AGAINST IT &#8221; &#8211; David Attenborough- Earth&#8217;s climate has changed throughout history. Just in the last 650,000 years there have been seven cycles of glacial advance and [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trytogiveback.org\/it\/climate_change_global_warming\/\" \/>\n<meta property=\"og:site_name\" content=\"Alveto Expedition\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T16:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/\",\"name\":\"Climate Change - Alveto Expedition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/climate-change-2254711_1280-1024x525.jpg\",\"datePublished\":\"2021-02-15T22:32:57+00:00\",\"dateModified\":\"2021-04-08T16:34:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/climate-change-2254711_1280-1024x525.jpg\",\"contentUrl\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/climate-change-2254711_1280-1024x525.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/climate_change_global_warming\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trytogiveback.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Climate Change\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#website\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/\",\"name\":\"Alveto Expedition\",\"description\":\"Be the Change you Want to see in the World\",\"publisher\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trytogiveback.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#organization\",\"name\":\"Try to Give Back\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/TRY-TO-GB-LOGO-blu-lighter.png\",\"contentUrl\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/TRY-TO-GB-LOGO-blu-lighter.png\",\"width\":7712,\"height\":2000,\"caption\":\"Try to Give Back\"},\"image\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/trytogiveback\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Climate Change - Alveto Expedition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trytogiveback.org\/it\/climate_change_global_warming\/","og_locale":"it_IT","og_type":"article","og_title":"Climate Change - Alveto Expedition","og_description":"CLIMATE CHANGE AND GLOBAL WARMING &#8221; IF WE HAVE BECOME POWERFUL ENOUGH TO CHANGE THE ENTIRE PLANET, THEN WE ARE POWERFUL ENOUGH TO WORK WITH NATURE RATHER THAN AGAINST IT &#8221; &#8211; David Attenborough- Earth&#8217;s climate has changed throughout history. Just in the last 650,000 years there have been seven cycles of glacial advance and [&hellip;]","og_url":"https:\/\/trytogiveback.org\/it\/climate_change_global_warming\/","og_site_name":"Alveto Expedition","article_modified_time":"2021-04-08T16:34:55+00:00","og_image":[{"url":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trytogiveback.org\/climate_change_global_warming\/","url":"https:\/\/trytogiveback.org\/climate_change_global_warming\/","name":"Climate Change - Alveto Expedition","isPartOf":{"@id":"https:\/\/trytogiveback.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trytogiveback.org\/climate_change_global_warming\/#primaryimage"},"image":{"@id":"https:\/\/trytogiveback.org\/climate_change_global_warming\/#primaryimage"},"thumbnailUrl":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg","datePublished":"2021-02-15T22:32:57+00:00","dateModified":"2021-04-08T16:34:55+00:00","breadcrumb":{"@id":"https:\/\/trytogiveback.org\/climate_change_global_warming\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trytogiveback.org\/climate_change_global_warming\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trytogiveback.org\/climate_change_global_warming\/#primaryimage","url":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg","contentUrl":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2021\/02\/climate-change-2254711_1280-1024x525.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/trytogiveback.org\/climate_change_global_warming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trytogiveback.org\/"},{"@type":"ListItem","position":2,"name":"Climate Change"}]},{"@type":"WebSite","@id":"https:\/\/trytogiveback.org\/#website","url":"https:\/\/trytogiveback.org\/","name":"Alveto Expedition","description":"Be the Change you Want to see in the World","publisher":{"@id":"https:\/\/trytogiveback.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trytogiveback.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/trytogiveback.org\/#organization","name":"Try to Give Back","url":"https:\/\/trytogiveback.org\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trytogiveback.org\/#\/schema\/logo\/image\/","url":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2020\/11\/TRY-TO-GB-LOGO-blu-lighter.png","contentUrl":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2020\/11\/TRY-TO-GB-LOGO-blu-lighter.png","width":7712,"height":2000,"caption":"Try to Give Back"},"image":{"@id":"https:\/\/trytogiveback.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/trytogiveback"]}]}},"campaignId":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages\/2684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/comments?post=2684"}],"version-history":[{"count":19,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages\/2684\/revisions"}],"predecessor-version":[{"id":2969,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages\/2684\/revisions\/2969"}],"wp:attachment":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/media?parent=2684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}