{"id":2364,"date":"2021-02-08T23:16:34","date_gmt":"2021-02-08T23:16:34","guid":{"rendered":"https:\/\/trytogiveback.org\/?page_id=2364"},"modified":"2021-02-08T23:19:18","modified_gmt":"2021-02-08T23:19:18","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/trytogiveback.org\/it\/cookie-policy\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2364\" class=\"elementor elementor-2364\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f59007c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f59007c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3eed3eb8\" data-id=\"3eed3eb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bbee9f3 elementor-widget elementor-widget-text-editor\" data-id=\"3bbee9f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"cli_pg_page_contaner\"><h3>Informazioni sulla politica dei cookie<\/h3><div><p>Questa Cookie Policy spiega cosa sono i cookie e come li utilizziamo, i tipi di cookie che utilizziamo cio\u00e8 le informazioni che raccogliamo utilizzando i cookie e come tali informazioni vengono utilizzate, e come controllare le preferenze dei cookie. Per ulteriori informazioni su come utilizziamo, conserviamo e teniamo al sicuro i vostri dati personali, consultate la nostra Privacy Policy.<\/p><p>Puoi in qualsiasi momento cambiare o ritirare il tuo consenso dalla Dichiarazione dei cookie sul nostro sito web<br \/>Scopri di pi\u00f9 su chi siamo, su come puoi contattarci e su come trattiamo i dati personali nella nostra politica sulla privacy.<br \/>Il tuo consenso si applica ai seguenti domini: trytogiveback.org<br \/><div class=\"cli_user_consent_state\">Il tuo stato attuale: Non \u00e8 stato concesso alcun consenso. <a class=\"cli_manage_current_consent\" style=\"cursor:pointer;text-decoration:underline;\">Gestisci il tuo consenso.<\/a> <\/div><\/p><\/div><h3>Cosa sono i cookies?<\/h3><div>I cookie sono piccoli file di testo che vengono utilizzati per memorizzare piccoli pezzi di informazioni. Vengono memorizzati sul tuo dispositivo quando il sito web viene caricato sul tuo browser. Questi cookie ci aiutano a far funzionare correttamente il sito web, a renderlo pi\u00f9 sicuro, a fornire una migliore esperienza all'utente e a capire come funziona il sito web e ad analizzare ci\u00f2 che funziona e dove deve essere migliorato.<\/div><h3>Come utilizziamo i cookies?<\/h3><div><p>Come la maggior parte dei servizi online, il nostro sito web utilizza cookie di prima parte e di terza parte per diversi scopi. I cookie di prima parte sono per lo pi\u00f9 necessari per il corretto funzionamento del sito, e non raccolgono alcun dato personale identificabile.<\/p><p>I cookie di terze parti utilizzati sul nostro sito web servono principalmente per capire come funziona il sito web, come si interagisce con il nostro sito web, mantenendo i nostri servizi sicuri, fornendo pubblicit\u00e0 che sono rilevanti per voi, e tutto sommato fornendovi una migliore e migliorata esperienza utente e aiutare a velocizzare le vostre future interazioni con il nostro sito web.<\/p><\/div><h3>Che tipo di cookies utilizziamo ?<\/h3><div><p>Essenziali: Alcuni cookie sono essenziali per permetterti di sperimentare la piena funzionalit\u00e0 del nostro sito. Ci permettono di mantenere le sessioni degli utenti e prevenire qualsiasi minaccia alla sicurezza. Non raccolgono o memorizzano alcuna informazione personale. Per esempio, questi cookie ti permettono di accedere al tuo account e aggiungere prodotti al tuo carrello, e di effettuare il checkout in modo sicuro.<\/p><p>Statistici: Questi cookie memorizzano informazioni come il numero di visitatori del sito, il numero di visitatori unici, quali pagine del sito sono state visitate, la fonte della visita, ecc. Questi dati ci aiutano a capire e analizzare come funziona il sito web e dove deve essere migliorato.<\/p><p>Marketing:  rilevanti se Il nostro sito web mostra annunci pubblicitari. Questi cookie sono utilizzati per personalizzare le pubblicit\u00e0 che ti mostriamo in modo che siano significative per te. Questi cookie ci aiutano anche a tenere traccia dell'efficienza di queste campagne pubblicitarie.<br \/>Le informazioni memorizzate in questi cookie possono anche essere utilizzate dai fornitori di annunci di terze parti per mostrarle annunci anche su altri siti web del browser.<\/p><p>Funzionali: Questi sono i cookie che aiutano alcune funzionalit\u00e0 non essenziali sul nostro sito web. Queste funzionalit\u00e0 includono l'incorporazione di contenuti come video o la condivisione di contenuti del sito web su piattaforme di social media.<\/p><p>Preferenziali: Questi cookie ci aiutano a memorizzare le tue impostazioni e preferenze di navigazione, come le preferenze di lingua, in modo che tu possa avere un'esperienza migliore ed efficiente nelle visite future al sito.<br \/><\/p><\/div><h3>Come puoi controllare le tue preferenze cookies?<\/h3><div><p>Se decidi di cambiare le tue preferenze pi\u00f9 tardi durante la tua sessione di navigazione, puoi cliccare sulla scheda \"Privacy &amp; Cookie Policy\" sul tuo schermo. Questo visualizzer\u00e0 nuovamente l'avviso di consenso consentendoti di modificare le tue preferenze o di ritirare completamente il tuo consenso.<\/p><p>Inoltre, diversi browser forniscono diversi metodi per bloccare ed eliminare i cookie utilizzati dai siti web. Puoi cambiare le impostazioni del tuo browser per bloccare\/eliminare i cookie. Per saperne di pi\u00f9 su come gestire ed eliminare i cookie, visita wikipedia.org, www.allaboutcookies.org.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>About this cookie policy This Cookie Policy explains what cookies are and how we use them, the types of cookies we use i.e, the information we collect using cookies and how that information is used, and how to control the cookie preferences. For further information on how we use, store, and keep your personal data [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2364","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie Policy - Alveto Expedition<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trytogiveback.org\/it\/cookie-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy - Alveto Expedition\" \/>\n<meta property=\"og:description\" content=\"About this cookie policy This Cookie Policy explains what cookies are and how we use them, the types of cookies we use i.e, the information we collect using cookies and how that information is used, and how to control the cookie preferences. For further information on how we use, store, and keep your personal data [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trytogiveback.org\/it\/cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Alveto Expedition\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T23:19:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trytogiveback.org\/wp-content\/uploads\/2020\/11\/TRY-TO-GB-LOGO-blu-lighter.png\" \/>\n\t<meta property=\"og:image:width\" content=\"7712\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/cookie-policy\\\/\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/cookie-policy\\\/\",\"name\":\"Cookie Policy - Alveto Expedition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#website\"},\"datePublished\":\"2021-02-08T23:16:34+00:00\",\"dateModified\":\"2021-02-08T23:19:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/cookie-policy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trytogiveback.org\\\/cookie-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/cookie-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trytogiveback.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#website\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/\",\"name\":\"Alveto Expedition\",\"description\":\"Be the Change you Want to see in the World\",\"publisher\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trytogiveback.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#organization\",\"name\":\"Try to Give Back\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/TRY-TO-GB-LOGO-blu-lighter.png\",\"contentUrl\":\"https:\\\/\\\/trytogiveback.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/TRY-TO-GB-LOGO-blu-lighter.png\",\"width\":7712,\"height\":2000,\"caption\":\"Try to Give Back\"},\"image\":{\"@id\":\"https:\\\/\\\/trytogiveback.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/trytogiveback\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie Policy - Alveto Expedition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trytogiveback.org\/it\/cookie-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Cookie Policy - Alveto Expedition","og_description":"About this cookie policy This Cookie Policy explains what cookies are and how we use them, the types of cookies we use i.e, the information we collect using cookies and how that information is used, and how to control the cookie preferences. For further information on how we use, store, and keep your personal data [&hellip;]","og_url":"https:\/\/trytogiveback.org\/it\/cookie-policy\/","og_site_name":"Alveto Expedition","article_modified_time":"2021-02-08T23:19:18+00:00","og_image":[{"width":7712,"height":2000,"url":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2020\/11\/TRY-TO-GB-LOGO-blu-lighter.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trytogiveback.org\/cookie-policy\/","url":"https:\/\/trytogiveback.org\/cookie-policy\/","name":"Cookie Policy - Alveto Expedition","isPartOf":{"@id":"https:\/\/trytogiveback.org\/#website"},"datePublished":"2021-02-08T23:16:34+00:00","dateModified":"2021-02-08T23:19:18+00:00","breadcrumb":{"@id":"https:\/\/trytogiveback.org\/cookie-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trytogiveback.org\/cookie-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/trytogiveback.org\/cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trytogiveback.org\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy"}]},{"@type":"WebSite","@id":"https:\/\/trytogiveback.org\/#website","url":"https:\/\/trytogiveback.org\/","name":"Alveto Expedition","description":"Be the Change you Want to see in the World","publisher":{"@id":"https:\/\/trytogiveback.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trytogiveback.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/trytogiveback.org\/#organization","name":"Try to Give Back","url":"https:\/\/trytogiveback.org\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trytogiveback.org\/#\/schema\/logo\/image\/","url":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2020\/11\/TRY-TO-GB-LOGO-blu-lighter.png","contentUrl":"https:\/\/trytogiveback.org\/wp-content\/uploads\/2020\/11\/TRY-TO-GB-LOGO-blu-lighter.png","width":7712,"height":2000,"caption":"Try to Give Back"},"image":{"@id":"https:\/\/trytogiveback.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/trytogiveback"]}]}},"campaignId":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages\/2364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/comments?post=2364"}],"version-history":[{"count":3,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages\/2364\/revisions"}],"predecessor-version":[{"id":2367,"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/pages\/2364\/revisions\/2367"}],"wp:attachment":[{"href":"https:\/\/trytogiveback.org\/it\/wp-json\/wp\/v2\/media?parent=2364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}